{"id":16347,"date":"2024-09-24T11:32:50","date_gmt":"2024-09-24T11:32:50","guid":{"rendered":"https:\/\/stepahead.pt\/?p=16347"},"modified":"2024-09-24T17:14:16","modified_gmt":"2024-09-24T17:14:16","slug":"banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud","status":"publish","type":"post","link":"https:\/\/stepahead.pt\/en\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/","title":{"rendered":"Banco BiG otimiza processos e aumenta efici\u00eancia com o Siga Cloud"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"16347\" class=\"elementor elementor-16347\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aad35e9 e-con-full e-flex e-con e-parent\" data-id=\"aad35e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4635a01 elementor-widget elementor-widget-image\" data-id=\"4635a01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/stepahead.pt\/wp-content\/uploads\/2024\/09\/bancobig-e-sigacloud.jpg\" class=\"attachment-full size-full wp-image-16389\" alt=\"Uma mulher a trabalhar no escritorio com varios monitores, as palavras &quot;Gestao Documental e de Processos: Efici\u00eancia e Agilidade&quot; como legenda\" srcset=\"https:\/\/stepahead.pt\/wp-content\/uploads\/2024\/09\/bancobig-e-sigacloud.jpg 1920w, https:\/\/stepahead.pt\/wp-content\/uploads\/2024\/09\/bancobig-e-sigacloud-300x169.jpg 300w, https:\/\/stepahead.pt\/wp-content\/uploads\/2024\/09\/bancobig-e-sigacloud-1024x576.jpg 1024w, https:\/\/stepahead.pt\/wp-content\/uploads\/2024\/09\/bancobig-e-sigacloud-768x432.jpg 768w, https:\/\/stepahead.pt\/wp-content\/uploads\/2024\/09\/bancobig-e-sigacloud-1536x864.jpg 1536w, https:\/\/stepahead.pt\/wp-content\/uploads\/2024\/09\/bancobig-e-sigacloud-18x10.jpg 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00d4a16 elementor-widget elementor-widget-text-editor\" data-id=\"00d4a16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Na sua jornada de transforma\u00e7\u00e3o digital, o <a href=\"https:\/\/www.big.pt\/\" target=\"_blank\" rel=\"noopener\"><u>Banco BiG<\/u><\/a> encontrou no <a href=\"https:\/\/stepahead.pt\/en\/solucoes\/gestao-documental-e-de-processos\/\"><u>Siga Cloud<\/u><\/a> powered by Step Ahead Consulting, a solu\u00e7\u00e3o de Gest\u00e3o Documental e de Processos ideal para otimizar os seus processos e aumentar a efici\u00eancia operacional.<\/p><p>Iniciada em 2013, a parceria entre o Banco BiG e a Step Ahead Consulting resultou na implementa\u00e7\u00e3o de um vasto conjunto de processos numa \u00f3tica multicanal, abrangendo toda a \u00e1rea operacional do banco, onde nos mais variados dom\u00ednios o SIGA Cloud se apresenta como uma solu\u00e7\u00e3o completa e eficiente na Gest\u00e3o Documental e orquestra\u00e7\u00e3o de processos.<\/p><p>A solu\u00e7\u00e3o implementada, por via da migra\u00e7\u00e3o de uma solu\u00e7\u00e3o anterior, permitiu ao Banco BiG ter uma vis\u00e3o 360\u00ba dos seus clientes, com um hist\u00f3rico detalhado de intera\u00e7\u00f5es entre estes e o banco, facilitando a personaliza\u00e7\u00e3o dos servi\u00e7os e a tomada de decis\u00f5es mais c\u00e9leres e assertivas.<\/p><p>Ao oferecer um atendimento mais r\u00e1pido e eficiente, a solu\u00e7\u00e3o eleva a experi\u00eancia do cliente e fortalece o relacionamento com a marca, resultando numa maior satisfa\u00e7\u00e3o e fideliza\u00e7\u00e3o. Ao otimizar processos e centrar-se na experi\u00eancia do utilizador, a solu\u00e7\u00e3o tamb\u00e9m contribui para a satisfa\u00e7\u00e3o dos colaboradores.<\/p><p>\u201cA implementa\u00e7\u00e3o do SIGA Cloud foi um dos pilares para a transforma\u00e7\u00e3o digital do Banco BiG. A solu\u00e7\u00e3o permitiu otimizar os nossos processos, aumentar a efici\u00eancia e melhorar a experi\u00eancia do cliente&#8221;, afirma Paulo Campos, Diretor de Opera\u00e7\u00f5es do Banco BiG.<\/p><p>O SIGA Cloud \u00e9 uma solu\u00e7\u00e3o de Gest\u00e3o Documental e de Processos totalmente parametriz\u00e1vel, flex\u00edvel e escal\u00e1vel, que permite a automatiza\u00e7\u00e3o de processos. Faz uso do Elastic Search para pesquisas em tempo recorde. Atrav\u00e9s da captura digital inteligente, ferramenta nativa e gratuita, permite digitalizar documentos em massa.<\/p><p>A capacidades de integra\u00e7\u00e3o com outros tipos de sistemas externos, tornam a solu\u00e7\u00e3o vantajosa de um ponto de vista de reposit\u00f3rio central de documenta\u00e7\u00e3o acelerando a concretiza\u00e7\u00e3o das consultas feitas pelos utilizadores.<\/p><p>Paulo Guerra, presidente do Conselho de Administra\u00e7\u00e3o da Step Ahead Consulting afirma que \u201cA proposta de valor do SIGA Cloud \u00e9 clara: Descomplica processos, tornando-os autom\u00e1ticos, eficientes e seguros. Converte o papel em digital e o manual em autom\u00e1tico, permitindo, atrav\u00e9s de uma solu\u00e7\u00e3o integrada, gerir o ciclo de vida de documentos e processos. Acess\u00edvel multidispositivo, 24\/7.&#8221;<\/p><p>A Step Ahead Consulting orgulha-se de continuar a apoiar o Banco BiG na sua jornada de transforma\u00e7\u00e3o digital, contribuindo para a cria\u00e7\u00e3o de um ambiente operacional mais eficiente, seguro e centrado no cliente.<\/p><p>Saiba mais sobre o <a href=\"https:\/\/stepahead.pt\/en\/solucoes\/gestao-documental-e-de-processos\/\"><u>functionalities<\/u><\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Parceria de sucesso impulsiona a transforma\u00e7\u00e3o digital e oferece vis\u00e3o 360\u00ba do cliente.<\/p>","protected":false},"author":3,"featured_media":16390,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-16347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Banco BiG otimiza processos e aumenta efici\u00eancia com o Siga Cloud - Step Ahead Consulting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stepahead.pt\/en\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Banco BiG otimiza processos e aumenta efici\u00eancia com o Siga Cloud - Step Ahead Consulting\" \/>\n<meta property=\"og:description\" content=\"Parceria de sucesso impulsiona a transforma\u00e7\u00e3o digital e oferece vis\u00e3o 360\u00ba do cliente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stepahead.pt\/en\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/\" \/>\n<meta property=\"og:site_name\" content=\"Step Ahead Consulting\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/StepAheadConsultingPortugal\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-24T11:32:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-24T17:14:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stepahead.pt\/wp-content\/uploads\/2024\/09\/bancobig-e-sigacloud-thumbnail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Inacio Amerio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@StepAheadCons\" \/>\n<meta name=\"twitter:site\" content=\"@StepAheadCons\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Inacio Amerio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stepahead.pt\\\/noticias\\\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepahead.pt\\\/noticias\\\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\\\/\"},\"author\":{\"name\":\"Inacio Amerio\",\"@id\":\"https:\\\/\\\/stepahead.pt\\\/#\\\/schema\\\/person\\\/4541529a50b438015497d54b1bab8b6b\"},\"headline\":\"Banco BiG otimiza processos e aumenta efici\u00eancia com o Siga Cloud\",\"datePublished\":\"2024-09-24T11:32:50+00:00\",\"dateModified\":\"2024-09-24T17:14:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stepahead.pt\\\/noticias\\\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\\\/\"},\"wordCount\":463,\"publisher\":{\"@id\":\"https:\\\/\\\/stepahead.pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/stepahead.pt\\\/noticias\\\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stepahead.pt\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/bancobig-e-sigacloud-thumbnail.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stepahead.pt\\\/noticias\\\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\\\/\",\"url\":\"https:\\\/\\\/stepahead.pt\\\/noticias\\\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\\\/\",\"name\":\"Banco BiG otimiza processos e aumenta efici\u00eancia com o Siga Cloud - Step Ahead Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stepahead.pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stepahead.pt\\\/noticias\\\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stepahead.pt\\\/noticias\\\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stepahead.pt\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/bancobig-e-sigacloud-thumbnail.jpg\",\"datePublished\":\"2024-09-24T11:32:50+00:00\",\"dateModified\":\"2024-09-24T17:14:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stepahead.pt\\\/noticias\\\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stepahead.pt\\\/noticias\\\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/stepahead.pt\\\/noticias\\\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stepahead.pt\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/bancobig-e-sigacloud-thumbnail.jpg\",\"contentUrl\":\"https:\\\/\\\/stepahead.pt\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/bancobig-e-sigacloud-thumbnail.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Uma mulher a trabalhar no escritorio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stepahead.pt\\\/noticias\\\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/stepahead.pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Banco BiG otimiza processos e aumenta efici\u00eancia com o Siga Cloud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stepahead.pt\\\/#website\",\"url\":\"https:\\\/\\\/stepahead.pt\\\/\",\"name\":\"Step Ahead Consulting\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/stepahead.pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stepahead.pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stepahead.pt\\\/#organization\",\"name\":\"Step Ahead Consulting\",\"url\":\"https:\\\/\\\/stepahead.pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/stepahead.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stepahead.pt\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/sac-favicon.svg\",\"contentUrl\":\"https:\\\/\\\/stepahead.pt\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/sac-favicon.svg\",\"width\":1754,\"height\":1754,\"caption\":\"Step Ahead Consulting\"},\"image\":{\"@id\":\"https:\\\/\\\/stepahead.pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/StepAheadConsultingPortugal\\\/\",\"https:\\\/\\\/x.com\\\/StepAheadCons\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/step-ahead-consulting-sa\\\/mycompany\\\/\",\"https:\\\/\\\/www.instagram.com\\\/stepaheadconsulting\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stepahead.pt\\\/#\\\/schema\\\/person\\\/4541529a50b438015497d54b1bab8b6b\",\"name\":\"Inacio Amerio\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Banco BiG otimiza processos e aumenta efici\u00eancia com o Siga Cloud - Step Ahead Consulting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stepahead.pt\/en\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/","og_locale":"en_US","og_type":"article","og_title":"Banco BiG otimiza processos e aumenta efici\u00eancia com o Siga Cloud - Step Ahead Consulting","og_description":"Parceria de sucesso impulsiona a transforma\u00e7\u00e3o digital e oferece vis\u00e3o 360\u00ba do cliente.","og_url":"https:\/\/stepahead.pt\/en\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/","og_site_name":"Step Ahead Consulting","article_publisher":"https:\/\/www.facebook.com\/StepAheadConsultingPortugal\/","article_published_time":"2024-09-24T11:32:50+00:00","article_modified_time":"2024-09-24T17:14:16+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/stepahead.pt\/wp-content\/uploads\/2024\/09\/bancobig-e-sigacloud-thumbnail.jpg","type":"image\/jpeg"}],"author":"Inacio Amerio","twitter_card":"summary_large_image","twitter_creator":"@StepAheadCons","twitter_site":"@StepAheadCons","twitter_misc":{"Written by":"Inacio Amerio","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stepahead.pt\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/#article","isPartOf":{"@id":"https:\/\/stepahead.pt\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/"},"author":{"name":"Inacio Amerio","@id":"https:\/\/stepahead.pt\/#\/schema\/person\/4541529a50b438015497d54b1bab8b6b"},"headline":"Banco BiG otimiza processos e aumenta efici\u00eancia com o Siga Cloud","datePublished":"2024-09-24T11:32:50+00:00","dateModified":"2024-09-24T17:14:16+00:00","mainEntityOfPage":{"@id":"https:\/\/stepahead.pt\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/"},"wordCount":463,"publisher":{"@id":"https:\/\/stepahead.pt\/#organization"},"image":{"@id":"https:\/\/stepahead.pt\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/#primaryimage"},"thumbnailUrl":"https:\/\/stepahead.pt\/wp-content\/uploads\/2024\/09\/bancobig-e-sigacloud-thumbnail.jpg","articleSection":["Not\u00edcias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/stepahead.pt\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/","url":"https:\/\/stepahead.pt\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/","name":"Banco BiG otimiza processos e aumenta efici\u00eancia com o Siga Cloud - Step Ahead Consulting","isPartOf":{"@id":"https:\/\/stepahead.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stepahead.pt\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/#primaryimage"},"image":{"@id":"https:\/\/stepahead.pt\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/#primaryimage"},"thumbnailUrl":"https:\/\/stepahead.pt\/wp-content\/uploads\/2024\/09\/bancobig-e-sigacloud-thumbnail.jpg","datePublished":"2024-09-24T11:32:50+00:00","dateModified":"2024-09-24T17:14:16+00:00","breadcrumb":{"@id":"https:\/\/stepahead.pt\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stepahead.pt\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stepahead.pt\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/#primaryimage","url":"https:\/\/stepahead.pt\/wp-content\/uploads\/2024\/09\/bancobig-e-sigacloud-thumbnail.jpg","contentUrl":"https:\/\/stepahead.pt\/wp-content\/uploads\/2024\/09\/bancobig-e-sigacloud-thumbnail.jpg","width":1280,"height":720,"caption":"Uma mulher a trabalhar no escritorio"},{"@type":"BreadcrumbList","@id":"https:\/\/stepahead.pt\/noticias\/banco-big-otimiza-processos-e-aumenta-eficiencia-com-o-siga-cloud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/stepahead.pt\/"},{"@type":"ListItem","position":2,"name":"Banco BiG otimiza processos e aumenta efici\u00eancia com o Siga Cloud"}]},{"@type":"WebSite","@id":"https:\/\/stepahead.pt\/#website","url":"https:\/\/stepahead.pt\/","name":"Step Ahead Consulting","description":"","publisher":{"@id":"https:\/\/stepahead.pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stepahead.pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/stepahead.pt\/#organization","name":"Step Ahead Consulting","url":"https:\/\/stepahead.pt\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/stepahead.pt\/#\/schema\/logo\/image\/","url":"https:\/\/stepahead.pt\/wp-content\/uploads\/2021\/09\/sac-favicon.svg","contentUrl":"https:\/\/stepahead.pt\/wp-content\/uploads\/2021\/09\/sac-favicon.svg","width":1754,"height":1754,"caption":"Step Ahead Consulting"},"image":{"@id":"https:\/\/stepahead.pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/StepAheadConsultingPortugal\/","https:\/\/x.com\/StepAheadCons","https:\/\/www.linkedin.com\/company\/step-ahead-consulting-sa\/mycompany\/","https:\/\/www.instagram.com\/stepaheadconsulting\/"]},{"@type":"Person","@id":"https:\/\/stepahead.pt\/#\/schema\/person\/4541529a50b438015497d54b1bab8b6b","name":"Inacio Amerio"}]}},"_links":{"self":[{"href":"https:\/\/stepahead.pt\/en\/wp-json\/wp\/v2\/posts\/16347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stepahead.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stepahead.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stepahead.pt\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/stepahead.pt\/en\/wp-json\/wp\/v2\/comments?post=16347"}],"version-history":[{"count":0,"href":"https:\/\/stepahead.pt\/en\/wp-json\/wp\/v2\/posts\/16347\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stepahead.pt\/en\/wp-json\/wp\/v2\/media\/16390"}],"wp:attachment":[{"href":"https:\/\/stepahead.pt\/en\/wp-json\/wp\/v2\/media?parent=16347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stepahead.pt\/en\/wp-json\/wp\/v2\/categories?post=16347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stepahead.pt\/en\/wp-json\/wp\/v2\/tags?post=16347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}